{"id":1380,"date":"2022-01-14T17:12:37","date_gmt":"2022-01-14T16:12:37","guid":{"rendered":"https:\/\/www.medecinenutritionetdanse.com\/lipofilling\/"},"modified":"2022-01-19T18:26:10","modified_gmt":"2022-01-19T17:26:10","slug":"lipofilling","status":"publish","type":"page","link":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lipofilling\/","title":{"rendered":"Lipofilling"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_start=\u00a0\u00bb#ffeeee\u00a0\u00bb background_color_gradient_end=\u00a0\u00bb#ffdddd\u00a0\u00bb background_enable_image=\u00a0\u00bboff\u00a0\u00bb parallax=\u00a0\u00bbon\u00a0\u00bb parallax_method=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.14.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_text_color=\u00a0\u00bb#333333&Prime; header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_3_text_color=\u00a0\u00bb#333333&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>Lipofilling<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb top_divider_color=\u00a0\u00bb#fafafa\u00a0\u00bb top_divider_height=\u00a0\u00bb50px\u00a0\u00bb top_divider_flip=\u00a0\u00bbvertical\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb26px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Illipofilling est une intervention chirurgicale comportant deux phases: la premi\u00e8re consiste \u00e0 pr\u00e9lever le tissu adipeux (graisse) des zones du corps o\u00f9 il est le plus repr\u00e9sent\u00e9, et la seconde consiste \u00e0 le transf\u00e9rer, apr\u00e8s un traitement appropri\u00e9, dans d\u2019autres r\u00e9gions du corps o\u00f9 il se trouve. il est d\u00e9ficient, tr\u00e8s souvent sur le visage mais aussi sur d\u2019autres sites corporels.<\/p>\n<p>Le tissu adipeux (graisse) est aspir\u00e9 des zones du corps dans lesquelles il est naturellement pr\u00e9sent en plus grande quantit\u00e9, tel que l&rsquo;abdomen, les hanches, les cuisses, les genoux. Ensuite, \u00e0 travers de petites canules reli\u00e9es \u00e0 des seringues, il est inject\u00e9 dans la zone \u00e0 remplir. Il s\u2019agit en fait d\u2019une greffe de tissu.<\/p>\n<p>Les r\u00e9sultats obtenus avec le lipofilling sont g\u00e9n\u00e9ralement durables et satisfaisants pour le patient.<\/p>\n<p>La seule limite de cette intervention est la r\u00e9absorption partielle des tissus adipeux transf\u00e9r\u00e9s. Il reste toutefois la seule technique valable pour certaines zones du corps qui ne peut pas \u00eatre trait\u00e9e avec des m\u00e9thodes alternatives, \u00e0 la fois dans le visage et dans le corps.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/wp-content\/uploads\/2022\/01\/medecine-nutrition-et-danse-lipofilling.jpg\u00a0\u00bb alt=\u00a0\u00bbmedecine-nutrition-et-danse-lipofilling\u00a0\u00bb title_text=\u00a0\u00bbmedecine-nutrition-et-danse-lipofilling\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_module=\u00a0\u00bb381&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFEEEE\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\">Consultation en medecine et chirurgie esthetique m\u00e9decine esth\u00e9tique<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/wp-content\/uploads\/2022\/01\/medecine-nutrition-et-danse-medicina-estetica.jpg\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/medecine-esthetique\/\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/medecine-esthetique\/\u00a0\u00bb button_text=\u00a0\u00bbM\u00c9DECINE ESTH\u00c9TIQUE\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb200px||200px||true|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb130px||130px||true|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/wp-content\/uploads\/2022\/01\/medecine-nutrition-et-danse-chirurgia-estetica.jpg\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/\u00a0\u00bb button_text=\u00a0\u00bbCHIRURGIE ESTH\u00c9TIQUE\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb200px||200px||true|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb130px||130px||true|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.14.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#E9E9E9&Prime; custom_padding=\u00a0\u00bb41px||0px|||\u00a0\u00bb saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb global_module=\u00a0\u00bb2897&Prime;][et_pb_row _builder_version=\u00a0\u00bb4.14.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\">D\u00c9COUVREZ NOS PRODUITS<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,1_4,1_4,1_4&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb1&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/wp-content\/uploads\/2022\/01\/medicine-nutrition-et-danse-make-up.jpg\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb26px\u00a0\u00bb header_2_font=\u00a0\u00bbDancing Script||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb50px||25px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Ligne<\/h2>\n<p style=\"text-align: center;\"><strong>MAKE-UP<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/boutique\/ligne-de-maquillage\/\u00a0\u00bb button_text=\u00a0\u00bbEN SAVOIR PLUS\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_font=\u00a0\u00bb|||on|||||\u00a0\u00bb custom_margin=\u00a0\u00bb||50px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/wp-content\/uploads\/2022\/01\/medicine-nutrition-et-danse-linea-corpo-e-capelli.jpg\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb26px\u00a0\u00bb header_2_font=\u00a0\u00bbDancing Script||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb50px||25px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Ligne<\/h2>\n<p style=\"text-align: center;\"><strong>CORPS ET CHEVEUX<br \/><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/boutique\/ligne-corps-et-cheveux\/\u00a0\u00bb button_text=\u00a0\u00bbEN SAVOIR PLUS\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_font=\u00a0\u00bb|||on|||||\u00a0\u00bb custom_margin=\u00a0\u00bb||50px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/wp-content\/uploads\/2022\/01\/medicine-nutrition-et-danse-linea-viso-e-labbra.jpg\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb26px\u00a0\u00bb header_2_font=\u00a0\u00bbDancing Script||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb50px||25px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Ligne<\/h2>\n<p style=\"text-align: center;\"><strong>VISAGE<br \/><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/boutique\/ligne-de-visage\/\u00a0\u00bb button_text=\u00a0\u00bbEN SAVOIR PLUS\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_font=\u00a0\u00bb|||on|||||\u00a0\u00bb custom_margin=\u00a0\u00bb||50px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/wp-content\/uploads\/2022\/01\/medicine-nutrition-et-danse-linea-dimagrimento-localizzato.jpg\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb26px\u00a0\u00bb header_2_font=\u00a0\u00bbDancing Script||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb50px||25px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Ligne<\/h2>\n<p style=\"text-align: center;\"><strong>MINCEUR<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/boutique\/ligne-minceur-localisee\/\u00a0\u00bb button_text=\u00a0\u00bbEN SAVOIR PLUS\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_font=\u00a0\u00bb|||on|||||\u00a0\u00bb custom_margin=\u00a0\u00bb||50px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.14.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_module=\u00a0\u00bb2288&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb36px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><strong>CONSULTATION M\u00c9DICALE ONLINE<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span style=\"font-size: 17px;\">Demandez une consultation en ligne en remplissant le formulaire:<\/span><\/p>\n<p><span><\/span><\/p>\n<p><span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_contact_form use_spam_service=\u00a0\u00bbon\u00a0\u00bb recaptcha_list=\u00a0\u00bbmedecinenutritionetdansecom|medecinenutritionetdansecom-0&Prime; email=\u00a0\u00bbinfo@medecinenutritionetdanse.com\u00a0\u00bb custom_message=\u00a0\u00bbRICHIESTA CONSULENZA MEDICA ONLINE:||et_pb_line_break_holder||||et_pb_line_break_holder||Nome: %%Nome%%||et_pb_line_break_holder||||et_pb_line_break_holder||Cognome: %%Cognome%%||et_pb_line_break_holder||||et_pb_line_break_holder||Anno di nascita: %%Anno%%||et_pb_line_break_holder||||et_pb_line_break_holder||Citt\u00e0: %%Citt\u00e0%%||et_pb_line_break_holder||||et_pb_line_break_holder||Indirizzo e-mail: %%E-mail%%||et_pb_line_break_holder||||et_pb_line_break_holder||Telefono: %%Telefono%%||et_pb_line_break_holder||||et_pb_line_break_holder||Motivo del consulto: %%Messaggio%%||et_pb_line_break_holder||||et_pb_line_break_holder||||et_pb_line_break_holder||Consenso: %%Consenso%%\u00a0\u00bb success_message=\u00a0\u00bbVotre message a \u00e9t\u00e9 envoy\u00e9 avec succ\u00e8s\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb _unique_id=\u00a0\u00bb6b680a6c-bd31-4d8e-84be-b398d61ca036&Prime; form_field_background_color=\u00a0\u00bb#FFEEEE\u00a0\u00bb form_field_text_color=\u00a0\u00bb#333333&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_contact_field field_id=\u00a0\u00bbNome\u00a0\u00bb field_title=\u00a0\u00bbPr\u00e9nom\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbCognome\u00a0\u00bb field_title=\u00a0\u00bbNom\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbAnno\u00a0\u00bb field_title=\u00a0\u00bbAnn\u00e9e de naissance\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbCitt\u00e0\u00a0\u00bb field_title=\u00a0\u00bbVille\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbE-mail\u00a0\u00bb field_title=\u00a0\u00bbE-mail\u00a0\u00bb field_type=\u00a0\u00bbemail\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbTelefono\u00a0\u00bb field_title=\u00a0\u00bbT\u00e9l\u00e9phoner\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbMessaggio\u00a0\u00bb field_title=\u00a0\u00bbRaison de la consultation\u00a0\u00bb field_type=\u00a0\u00bbtext\u00a0\u00bb fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbConsenso\u00a0\u00bb field_title=\u00a0\u00bbDEMANDE DE CONSENTEMENT AU TRAITEMENT DE DONN\u00c9ES PERSONNELLES\u00a0\u00bb field_type=\u00a0\u00bbcheckbox\u00a0\u00bb checkbox_options=\u00a0\u00bb%91{%22value%22:%22En soumettant ce formulaire, vous consentez au traitement des donn\u00e9es uniquement pour la demande en question selon les conditions exprim\u00e9es sur la page politique de confidentialit\u00e9 *%22,%22checked%22:0,%22dragID%22:-1}%93&Prime; fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LipofillingIllipofilling est une intervention chirurgicale comportant deux phases: la premi\u00e8re consiste \u00e0 pr\u00e9lever le tissu adipeux (graisse) des zones du corps o\u00f9 il est le plus repr\u00e9sent\u00e9, et la seconde consiste \u00e0 le transf\u00e9rer, apr\u00e8s un traitement appropri\u00e9, dans d\u2019autres r\u00e9gions du corps o\u00f9 il se trouve. il est d\u00e9ficient, tr\u00e8s souvent sur le visage [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1508,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1380","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lipofilling - Medecine Nutrition et Danse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lipofilling\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lipofilling - Medecine Nutrition et Danse\" \/>\n<meta property=\"og:description\" content=\"LipofillingIllipofilling est une intervention chirurgicale comportant deux phases: la premi\u00e8re consiste \u00e0 pr\u00e9lever le tissu adipeux (graisse) des zones du corps o\u00f9 il est le plus repr\u00e9sent\u00e9, et la seconde consiste \u00e0 le transf\u00e9rer, apr\u00e8s un traitement appropri\u00e9, dans d\u2019autres r\u00e9gions du corps o\u00f9 il se trouve. il est d\u00e9ficient, tr\u00e8s souvent sur le visage [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lipofilling\/\" \/>\n<meta property=\"og:site_name\" content=\"Medecine Nutrition et Danse\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-19T17:26:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/fr\\\/chirurgie-esthetique\\\/lipofilling\\\/\",\"url\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/fr\\\/chirurgie-esthetique\\\/lipofilling\\\/\",\"name\":\"Lipofilling - Medecine Nutrition et Danse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/#website\"},\"datePublished\":\"2022-01-14T16:12:37+00:00\",\"dateModified\":\"2022-01-19T17:26:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/fr\\\/chirurgie-esthetique\\\/lipofilling\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/fr\\\/chirurgie-esthetique\\\/lipofilling\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/fr\\\/chirurgie-esthetique\\\/lipofilling\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CHIRURGIE ESTH\u00c9TIQUE\",\"item\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/fr\\\/chirurgie-esthetique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lipofilling\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/#website\",\"url\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/\",\"name\":\"Medecine Nutrition et Danse\",\"description\":\"Dott.ssa Monica Caddeo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lipofilling - Medecine Nutrition et Danse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lipofilling\/","og_locale":"fr_FR","og_type":"article","og_title":"Lipofilling - Medecine Nutrition et Danse","og_description":"LipofillingIllipofilling est une intervention chirurgicale comportant deux phases: la premi\u00e8re consiste \u00e0 pr\u00e9lever le tissu adipeux (graisse) des zones du corps o\u00f9 il est le plus repr\u00e9sent\u00e9, et la seconde consiste \u00e0 le transf\u00e9rer, apr\u00e8s un traitement appropri\u00e9, dans d\u2019autres r\u00e9gions du corps o\u00f9 il se trouve. il est d\u00e9ficient, tr\u00e8s souvent sur le visage [&hellip;]","og_url":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lipofilling\/","og_site_name":"Medecine Nutrition et Danse","article_modified_time":"2022-01-19T17:26:10+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lipofilling\/","url":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lipofilling\/","name":"Lipofilling - Medecine Nutrition et Danse","isPartOf":{"@id":"https:\/\/www.medecinenutritionetdanse.com\/#website"},"datePublished":"2022-01-14T16:12:37+00:00","dateModified":"2022-01-19T17:26:10+00:00","breadcrumb":{"@id":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lipofilling\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lipofilling\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lipofilling\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.medecinenutritionetdanse.com\/fr\/"},{"@type":"ListItem","position":2,"name":"CHIRURGIE ESTH\u00c9TIQUE","item":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/"},{"@type":"ListItem","position":3,"name":"Lipofilling"}]},{"@type":"WebSite","@id":"https:\/\/www.medecinenutritionetdanse.com\/#website","url":"https:\/\/www.medecinenutritionetdanse.com\/","name":"Medecine Nutrition et Danse","description":"Dott.ssa Monica Caddeo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medecinenutritionetdanse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/pages\/1380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/comments?post=1380"}],"version-history":[{"count":50,"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/pages\/1380\/revisions"}],"predecessor-version":[{"id":2911,"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/pages\/1380\/revisions\/2911"}],"up":[{"embeddable":true,"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/pages\/1508"}],"wp:attachment":[{"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/media?parent=1380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}