{"id":6335,"date":"2022-04-14T15:23:08","date_gmt":"2022-04-14T13:23:08","guid":{"rendered":"https:\/\/www.medecinenutritionetdanse.com\/chirurgie-esthetique\/lip-lift\/"},"modified":"2022-04-14T15:25:43","modified_gmt":"2022-04-14T13:25:43","slug":"lip-lift","status":"publish","type":"page","link":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lip-lift\/","title":{"rendered":"Lip Lift"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bb#ffeeee 0%|#ffdddd 100%\u00a0\u00bb background_color_gradient_start=\u00a0\u00bb#ffeeee\u00a0\u00bb background_color_gradient_end=\u00a0\u00bb#ffdddd\u00a0\u00bb background_enable_image=\u00a0\u00bboff\u00a0\u00bb parallax=\u00a0\u00bbon\u00a0\u00bb parallax_method=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_text_color=\u00a0\u00bb#333333&Prime; header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_3_text_color=\u00a0\u00bb#333333&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>Lip Lift : l<span>ifting direct des l\u00e8vres<\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb||24px|||\u00a0\u00bb top_divider_color=\u00a0\u00bb#fafafa\u00a0\u00bb top_divider_height=\u00a0\u00bb50px\u00a0\u00bb top_divider_flip=\u00a0\u00bbvertical\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||14px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb26px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Le lifting direct des l\u00e8vres, \u00e9galement appel\u00e9 lifting des l\u00e8vres, est une intervention chirurgicale visant \u00e0 r\u00e9duire la dimension verticale de la l\u00e8vre sup\u00e9rieure et, en m\u00eame temps, \u00e0 augmenter son volume.<\/p>\n<p>Cette chirurgie implique le retrait d&rsquo;une petite bande de peau, pr\u00e9cis\u00e9ment celle qui se trouve au-dessus du muscle labial, de cette mani\u00e8re une \u00e9version de la muqueuse elle-m\u00eame sera cr\u00e9\u00e9e qui donnera un aspect plus volumineux et charnu aux l\u00e8vres elles-m\u00eames.<\/p>\n<p>Gr\u00e2ce \u00e0 cette incision, une petite partie de la peau et du sous-cutan\u00e9 sera retir\u00e9e et la l\u00e8vre sup\u00e9rieure pourra \u00eatre tir\u00e9e vers le haut en soulevant son bord.<\/p>\n<p>Ce faisant, la l\u00e8vre deviendra plus haute et plus \u00e9vidente et son dessin naturel pourra \u00eatre modifi\u00e9 en modifiant l&rsquo;ARC DE CUPIDON, obtenant ainsi des l\u00e8vres plus voluptueuses et charnues.<\/p>\n<p>L&rsquo;am\u00e9lioration sera tr\u00e8s \u00e9vidente non seulement de face mais aussi de c\u00f4t\u00e9.<\/p>\n<p>Le lifting des l\u00e8vres est r\u00e9alis\u00e9 sous anesth\u00e9sie locale dans une clinique externe chirurgicale.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/wp-content\/uploads\/2022\/04\/Lip-lift.jpg\u00a0\u00bb alt=\u00a0\u00bbLip lift\u00a0\u00bb title_text=\u00a0\u00bbLip lift\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.17.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb16px||21px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.17.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>La dur\u00e9e de cette intervention est de 15-20 minutes et permet un retour imm\u00e9diat \u00e0 la vie quotidienne.<\/p>\n<p>De petits points sont utilis\u00e9s qui seront enlev\u00e9s apr\u00e8s 5 jours.<\/p>\n<p>Il ne s&rsquo;agit pas d&rsquo;ecchymoses mais seulement d&rsquo;un l\u00e9ger gonflement de la l\u00e8vre sup\u00e9rieure qui dispara\u00eetra en 4 \u00e0 5 jours.<\/p>\n<p>La chirurgie de L\u00c8VRE SUP\u00c9RIEURE ne comporte aucun risque ni complication majeure. Il faudra seulement faire attention \u00e0 la bonne cicatrisation de la cicatrice chirurgicale qui devient g\u00e9n\u00e9ralement invisible en quelques semaines<\/p>\n<p>Le r\u00e9sultat sera d\u00e9finitif<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.14.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_module=\u00a0\u00bb381&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFEEEE\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\">Consultation en medecine et chirurgie esthetique m\u00e9decine esth\u00e9tique<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/wp-content\/uploads\/2022\/01\/medecine-nutrition-et-danse-medicina-estetica.jpg\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/medecine-esthetique\/\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/medecine-esthetique\/\u00a0\u00bb button_text=\u00a0\u00bbM\u00c9DECINE ESTH\u00c9TIQUE\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb200px||200px||true|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb130px||130px||true|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/wp-content\/uploads\/2022\/01\/medecine-nutrition-et-danse-chirurgia-estetica.jpg\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/\u00a0\u00bb button_text=\u00a0\u00bbCHIRURGIE ESTH\u00c9TIQUE\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb200px||200px||true|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb130px||130px||true|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.14.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#E9E9E9&Prime; custom_padding=\u00a0\u00bb41px||0px|||\u00a0\u00bb global_module=\u00a0\u00bb2897&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text admin_label=\u00a0\u00bbTesto\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3 style=\"text-align: center;\">D\u00c9COUVREZ NOS PRODUITS<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,1_4,1_4,1_4&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb1&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/wp-content\/uploads\/2022\/01\/medicine-nutrition-et-danse-make-up.jpg\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb26px\u00a0\u00bb header_2_font=\u00a0\u00bbDancing Script||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb50px||25px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Ligne<\/h2>\n<p style=\"text-align: center;\"><strong>MAKE-UP<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/boutique\/ligne-de-maquillage\/\u00a0\u00bb button_text=\u00a0\u00bbEN SAVOIR PLUS\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_font=\u00a0\u00bb|||on|||||\u00a0\u00bb custom_margin=\u00a0\u00bb||50px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/wp-content\/uploads\/2022\/01\/medicine-nutrition-et-danse-linea-corpo-e-capelli.jpg\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb26px\u00a0\u00bb header_2_font=\u00a0\u00bbDancing Script||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb50px||25px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Ligne<\/h2>\n<p style=\"text-align: center;\"><strong>CORPS ET CHEVEUX<br \/><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/boutique\/ligne-corps-et-cheveux\/\u00a0\u00bb button_text=\u00a0\u00bbEN SAVOIR PLUS\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_font=\u00a0\u00bb|||on|||||\u00a0\u00bb custom_margin=\u00a0\u00bb||50px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/wp-content\/uploads\/2022\/01\/medicine-nutrition-et-danse-linea-viso-e-labbra.jpg\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb26px\u00a0\u00bb header_2_font=\u00a0\u00bbDancing Script||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb50px||25px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Ligne<\/h2>\n<p style=\"text-align: center;\"><strong>VISAGE<br \/><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/boutique\/ligne-de-visage\/\u00a0\u00bb button_text=\u00a0\u00bbEN SAVOIR PLUS\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_font=\u00a0\u00bb|||on|||||\u00a0\u00bb custom_margin=\u00a0\u00bb||50px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/wp-content\/uploads\/2022\/01\/medicine-nutrition-et-danse-linea-dimagrimento-localizzato.jpg\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb26px\u00a0\u00bb header_2_font=\u00a0\u00bbDancing Script||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb50px||25px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Ligne<\/h2>\n<p style=\"text-align: center;\"><strong>MINCEUR<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.medecinenutritionetdanse.com\/fr\/boutique\/ligne-minceur-localisee\/\u00a0\u00bb button_text=\u00a0\u00bbEN SAVOIR PLUS\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_font=\u00a0\u00bb|||on|||||\u00a0\u00bb custom_margin=\u00a0\u00bb||50px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.15&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_module=\u00a0\u00bb2288&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb36px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><strong>CONSULTATION M\u00c9DICALE ONLINE<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_contact_form use_spam_service=\u00a0\u00bbon\u00a0\u00bb recaptcha_list=\u00a0\u00bbmedecinenutritionetdansecom|medecinenutritionetdansecom-0&Prime; email=\u00a0\u00bbinfo@medecinenutritionetdanse.com\u00a0\u00bb custom_message=\u00a0\u00bbRICHIESTA CONSULENZA MEDICA ONLINE:||et_pb_line_break_holder||||et_pb_line_break_holder||Nome: %%Nome%%||et_pb_line_break_holder||||et_pb_line_break_holder||Cognome: %%Cognome%%||et_pb_line_break_holder||||et_pb_line_break_holder||Anno di nascita: %%Anno%%||et_pb_line_break_holder||||et_pb_line_break_holder||Citt\u00e0: %%Citt\u00e0%%||et_pb_line_break_holder||||et_pb_line_break_holder||Indirizzo e-mail: %%E-mail%%||et_pb_line_break_holder||||et_pb_line_break_holder||Telefono: %%Telefono%%||et_pb_line_break_holder||||et_pb_line_break_holder||Motivo del consulto: %%Messaggio%%||et_pb_line_break_holder||||et_pb_line_break_holder||||et_pb_line_break_holder||Consenso: %%Consenso%%\u00a0\u00bb success_message=\u00a0\u00bbVotre message a \u00e9t\u00e9 envoy\u00e9 avec succ\u00e8s\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb _unique_id=\u00a0\u00bb6b680a6c-bd31-4d8e-84be-b398d61ca036&Prime; form_field_background_color=\u00a0\u00bb#FFEEEE\u00a0\u00bb form_field_text_color=\u00a0\u00bb#333333&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_contact_field field_id=\u00a0\u00bbNome\u00a0\u00bb field_title=\u00a0\u00bbPr\u00e9nom\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbCognome\u00a0\u00bb field_title=\u00a0\u00bbNom\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbAnno\u00a0\u00bb field_title=\u00a0\u00bbAnn\u00e9e de naissance\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbCitt\u00e0\u00a0\u00bb field_title=\u00a0\u00bbVille\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbE-mail\u00a0\u00bb field_title=\u00a0\u00bbE-mail\u00a0\u00bb field_type=\u00a0\u00bbemail\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbTelefono\u00a0\u00bb field_title=\u00a0\u00bbT\u00e9l\u00e9phoner\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbMessaggio\u00a0\u00bb field_title=\u00a0\u00bbRaison de la consultation\u00a0\u00bb field_type=\u00a0\u00bbtext\u00a0\u00bb fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00a0\u00bbConsenso\u00a0\u00bb field_title=\u00a0\u00bbDEMANDE DE CONSENTEMENT AU TRAITEMENT DE DONN\u00c9ES PERSONNELLES\u00a0\u00bb field_type=\u00a0\u00bbcheckbox\u00a0\u00bb checkbox_options=\u00a0\u00bb%91{%22value%22:%22En soumettant ce formulaire, vous consentez au traitement des donn\u00e9es uniquement pour la demande en question selon les conditions exprim\u00e9es sur la page politique de confidentialit\u00e9 *%22,%22checked%22:0,%22dragID%22:-1}%93&Prime; fullwidth_field=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lip Lift : lifting direct des l\u00e8vresLe lifting direct des l\u00e8vres, \u00e9galement appel\u00e9 lifting des l\u00e8vres, est une intervention chirurgicale visant \u00e0 r\u00e9duire la dimension verticale de la l\u00e8vre sup\u00e9rieure et, en m\u00eame temps, \u00e0 augmenter son volume. Cette chirurgie implique le retrait d&rsquo;une petite bande de peau, pr\u00e9cis\u00e9ment celle qui se trouve au-dessus du [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1508,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-6335","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lip Lift - Medecine Nutrition et Danse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lip-lift\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lip Lift - Medecine Nutrition et Danse\" \/>\n<meta property=\"og:description\" content=\"Lip Lift : lifting direct des l\u00e8vresLe lifting direct des l\u00e8vres, \u00e9galement appel\u00e9 lifting des l\u00e8vres, est une intervention chirurgicale visant \u00e0 r\u00e9duire la dimension verticale de la l\u00e8vre sup\u00e9rieure et, en m\u00eame temps, \u00e0 augmenter son volume. Cette chirurgie implique le retrait d&#039;une petite bande de peau, pr\u00e9cis\u00e9ment celle qui se trouve au-dessus du [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lip-lift\/\" \/>\n<meta property=\"og:site_name\" content=\"Medecine Nutrition et Danse\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-14T13:25:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/fr\\\/chirurgie-esthetique\\\/lip-lift\\\/\",\"url\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/fr\\\/chirurgie-esthetique\\\/lip-lift\\\/\",\"name\":\"Lip Lift - Medecine Nutrition et Danse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/#website\"},\"datePublished\":\"2022-04-14T13:23:08+00:00\",\"dateModified\":\"2022-04-14T13:25:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/fr\\\/chirurgie-esthetique\\\/lip-lift\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/fr\\\/chirurgie-esthetique\\\/lip-lift\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/fr\\\/chirurgie-esthetique\\\/lip-lift\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CHIRURGIE ESTH\u00c9TIQUE\",\"item\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/fr\\\/chirurgie-esthetique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lip Lift\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/#website\",\"url\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/\",\"name\":\"Medecine Nutrition et Danse\",\"description\":\"Dott.ssa Monica Caddeo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medecinenutritionetdanse.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lip Lift - Medecine Nutrition et Danse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lip-lift\/","og_locale":"fr_FR","og_type":"article","og_title":"Lip Lift - Medecine Nutrition et Danse","og_description":"Lip Lift : lifting direct des l\u00e8vresLe lifting direct des l\u00e8vres, \u00e9galement appel\u00e9 lifting des l\u00e8vres, est une intervention chirurgicale visant \u00e0 r\u00e9duire la dimension verticale de la l\u00e8vre sup\u00e9rieure et, en m\u00eame temps, \u00e0 augmenter son volume. Cette chirurgie implique le retrait d'une petite bande de peau, pr\u00e9cis\u00e9ment celle qui se trouve au-dessus du [&hellip;]","og_url":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lip-lift\/","og_site_name":"Medecine Nutrition et Danse","article_modified_time":"2022-04-14T13:25:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lip-lift\/","url":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lip-lift\/","name":"Lip Lift - Medecine Nutrition et Danse","isPartOf":{"@id":"https:\/\/www.medecinenutritionetdanse.com\/#website"},"datePublished":"2022-04-14T13:23:08+00:00","dateModified":"2022-04-14T13:25:43+00:00","breadcrumb":{"@id":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lip-lift\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lip-lift\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/lip-lift\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.medecinenutritionetdanse.com\/fr\/"},{"@type":"ListItem","position":2,"name":"CHIRURGIE ESTH\u00c9TIQUE","item":"https:\/\/www.medecinenutritionetdanse.com\/fr\/chirurgie-esthetique\/"},{"@type":"ListItem","position":3,"name":"Lip Lift"}]},{"@type":"WebSite","@id":"https:\/\/www.medecinenutritionetdanse.com\/#website","url":"https:\/\/www.medecinenutritionetdanse.com\/","name":"Medecine Nutrition et Danse","description":"Dott.ssa Monica Caddeo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medecinenutritionetdanse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/pages\/6335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/comments?post=6335"}],"version-history":[{"count":7,"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/pages\/6335\/revisions"}],"predecessor-version":[{"id":6343,"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/pages\/6335\/revisions\/6343"}],"up":[{"embeddable":true,"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/pages\/1508"}],"wp:attachment":[{"href":"https:\/\/www.medecinenutritionetdanse.com\/fr\/wp-json\/wp\/v2\/media?parent=6335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}